{"id":332,"date":"2025-04-28T14:11:09","date_gmt":"2025-04-28T17:11:09","guid":{"rendered":"https:\/\/faq.uol.com.br\/uolpd\/vou_perder_acesso_ao_meu_bol_mail_\/"},"modified":"2025-04-28T14:11:10","modified_gmt":"2025-04-28T17:11:10","slug":"vou-perder-acesso-ao-meu-bol-mail","status":"publish","type":"post","link":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/","title":{"rendered":"Vou perder acesso ao meu BOL Mail?"},"content":{"rendered":"<p><strong>N&atilde;o.<\/strong>&nbsp;Voc&ecirc; continuar&aacute; com o acesso ao&nbsp;<strong>BOL Mail gratuito<\/strong>&nbsp;e poder&aacute; acess&aacute;-lo e utiliz&aacute;-lo&nbsp;<strong>somente pelo navegador<\/strong>&nbsp;de sua prefer&ecirc;ncia por meio do site do <a href=\"https:\/\/bol.uol.com.br\" target=\"_blank\" rel=\"noopener\">BOL<\/a> ou diretamente acessando o&nbsp;<a href=\"https:\/\/nam02.safelinks.protection.outlook.com\/?url=https%3A%2F%2Femail.bol.uol.com.br%2Flogin&amp;data=04%7C01%7Crblaz%40uolinc.com%7C336a31d9bc644dfcb95608d8d9cd9431%7C7575b092fc5f4f6cb7a59e9ef7aca80d%7C1%7C0%7C637498824262851502%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=ZhZ%2Bti8HyJO7CyaADS3S1QjBzM43YRqXAonGHLBVhSs%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener\">Webmail BOL<\/a>. Por&eacute;m, as contas<strong> BOL Mail gratuito<\/strong> sofrer&atilde;o as seguintes mudan&ccedil;as:<\/p>\n<ul>\n<li>N&atilde;o ser&atilde;o mais acessadas pelo aplicativo<strong> BOL Mail <\/strong>e<strong> <\/strong>gerenciadores de e-mail como Outlook, Thunderbird e etc.;<\/li>\n<li>O espa&ccedil;o da caixa de e-mail <strong>ser&aacute; de 200MB<\/strong>;<\/li>\n<li>N&atilde;o ser&aacute; poss&iacute;vel criar redirecionamento de e-mails do BOL para outra conta de e-mail;<\/li>\n<li>N&atilde;o ser&aacute; poss&iacute;vel alterar a forma de visualiza&ccedil;&atilde;o em lista das mensagens.<\/li>\n<\/ul>\n<p>Para acessar seu e-mail BOL agora, <a href=\"http:\/\/email.bol.uol.com.br\/login#\" target=\"_blank\" rel=\"noopener\">clique aqui<\/a>. Em seguida, insira seu e-mail <strong>BOL <\/strong>e senha e clique em <strong>&quot;Entrar&quot;<\/strong>.<\/p>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png\" style=\"width: 45%;height: 45%\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Informa&ccedil;&otilde;es importantes: <\/strong><\/p>\n<ul>\n<li>Se houver redirecionamento configurado, ele deixar&aacute; de funcionar.<\/li>\n<li>Para verificar quanto do espa&ccedil;o da caixa de e-mail BOL j&aacute; foi utilizado, acesse o <a href=\"https:\/\/nam02.safelinks.protection.outlook.com\/?url=https%3A%2F%2Femail.bol.uol.com.br%2Flogin&amp;data=04%7C01%7Crblaz%40uolinc.com%7C336a31d9bc644dfcb95608d8d9cd9431%7C7575b092fc5f4f6cb7a59e9ef7aca80d%7C1%7C0%7C637498824262851502%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=ZhZ%2Bti8HyJO7CyaADS3S1QjBzM43YRqXAonGHLBVhSs%3D&amp;reserved=0\" target=\"_blank\" rel=\"noopener\">Webmail BOL<\/a>&nbsp;e, em seguida, no canto superior direito da tela inicial <strong>(conforme imagem abaixo)<\/strong>, ser&aacute; mostrado o espa&ccedil;o total da caixa e quanto desse espa&ccedil;o foi utilizado;<\/li>\n<\/ul>\n<p><img decoding=\"async\" alt=\"\" src=\"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/1b\/2022\/09\/14\/img-2---vou-perder-acesso-ao-meu-bol-mail-1663175308322_1366x579.png\" style=\"width: 65%;height: 65%\" \/><\/p>\n<p>Caso atualmente tenha<strong> ultrapassado os 200MB<\/strong> de espa&ccedil;o em seu e-mail, <u>voc&ecirc; dever&aacute; liberar espa&ccedil;o<\/u>, excluindo mensagens desnecess&aacute;rias, rascunhos, caixa de quarentena e lixeira,&nbsp;<u>para continuar enviando e recebendo e-mails<\/u>.<\/p>\n<p><strong>Aten&ccedil;&atilde;o!&nbsp;<\/strong>Caso sua caixa de e-mail BOL tenha ultrapassado os 200MB, as mensagens <u><strong>n&atilde;o ser&atilde;o<\/strong><\/u> apagadas, mas voc&ecirc; n&atilde;o conseguir&aacute; enviar ou receber e-mails, at&eacute; que apague as mensagens que excedem o limite de 200MB.<\/p>\n<p>Adquira o plano <a href=\"https:\/\/conta.uol.com.br\/login?t=bol&amp;&amp;signin=https%3A%2F%2Fcheckout.uol.com.br%2F%23%2FBOL%2F0%3Fpromotion%3DPROMPKSC3344&amp;dest=https%3A%2F%2Fcheckout.uol.com.br%2F%23%2FBOL%2F0%3Fpromotion%3DPROMPKSC3344\" target=\"_blank\" rel=\"noopener\"><strong>BOL Completo<\/strong><\/a> para ter 18GB de espa&ccedil;o em sua caixa, todos os recursos do e-mail, continuar com os acessos ao aplicativo BOL Mail e aos gerenciadores de e-mail, suporte telef&ocirc;nico sempre que precisar e, ainda, o Clube UOL, um clube de vantagens e descontos para economizar em suas compras. O plano <strong>BOL Completo<\/strong> &eacute; mensal e <u>n&atilde;o possui fidelidade<\/u>.<\/p>\n<p>&nbsp;<\/p>\n<p>Est&aacute; com dificuldade na contrata&ccedil;&atilde;o do plano <strong>BOL Completo?<\/strong> Acesse nosso <strong>chat online<\/strong> clicando <a href=\"https:\/\/chatvendas.uol.com.br\/ChatWEB\/AbrirTelaCriarChat.do?site=5&amp;utm_source=BOL&amp;utm_medium=Chat&amp;utm_campaign=Vendas\" target=\"_blank\" rel=\"noopener\">aqui<\/a> e fale j&aacute; com um de nossos especialistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N&atilde;o.&nbsp;Voc&ecirc; continuar&aacute; com o acesso ao&nbsp;BOL Mail gratuito&nbsp;e poder&aacute; acess&aacute;-lo e utiliz&aacute;-lo&nbsp;somente pelo navegador&nbsp;de sua prefer&ecirc;ncia por meio do site do BOL ou diretamente acessando o&nbsp;Webmail BOL. Por&eacute;m, as contas BOL Mail gratuito sofrer&atilde;o as seguintes mudan&ccedil;as: N&atilde;o ser&atilde;o mais acessadas pelo aplicativo BOL Mail e gerenciadores de e-mail como Outlook, Thunderbird e etc.; O [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"article_uolpd","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vou perder acesso ao meu BOL Mail? - FAQ UOL Produtos Digitais<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vou perder acesso ao meu BOL Mail? - FAQ UOL Produtos Digitais\" \/>\n<meta property=\"og:description\" content=\"N&atilde;o.&nbsp;Voc&ecirc; continuar&aacute; com o acesso ao&nbsp;BOL Mail gratuito&nbsp;e poder&aacute; acess&aacute;-lo e utiliz&aacute;-lo&nbsp;somente pelo navegador&nbsp;de sua prefer&ecirc;ncia por meio do site do BOL ou diretamente acessando o&nbsp;Webmail BOL. Por&eacute;m, as contas BOL Mail gratuito sofrer&atilde;o as seguintes mudan&ccedil;as: N&atilde;o ser&atilde;o mais acessadas pelo aplicativo BOL Mail e gerenciadores de e-mail como Outlook, Thunderbird e etc.; O [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/\" \/>\n<meta property=\"og:site_name\" content=\"FAQ UOL Produtos Digitais\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T17:11:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T17:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/person\/ca471cdebf5cc77ad5e5060a3aad80c8\"},\"headline\":\"Vou perder acesso ao meu BOL Mail?\",\"datePublished\":\"2025-04-28T17:11:09+00:00\",\"dateModified\":\"2025-04-28T17:11:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#organization\"},\"image\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png\",\"articleSection\":[\"Bol mail\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/\",\"url\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/\",\"name\":\"Vou perder acesso ao meu BOL Mail? - FAQ UOL Produtos Digitais\",\"isPartOf\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png\",\"datePublished\":\"2025-04-28T17:11:09+00:00\",\"dateModified\":\"2025-04-28T17:11:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#primaryimage\",\"url\":\"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png\",\"contentUrl\":\"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/faq.uol.com.br\/uolpd\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vou perder acesso ao meu BOL Mail?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#website\",\"url\":\"https:\/\/faq.uol.com.br\/uolpd\/\",\"name\":\"FAQ UOL Produtos Digitais\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/faq.uol.com.br\/uolpd\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#organization\",\"name\":\"FAQ UOL Produtos Digitais\",\"url\":\"https:\/\/faq.uol.com.br\/uolpd\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/faq.uol.com.br\/uolpd\/wp-content\/uploads\/sites\/3\/2024\/05\/favicon.png\",\"contentUrl\":\"https:\/\/faq.uol.com.br\/uolpd\/wp-content\/uploads\/sites\/3\/2024\/05\/favicon.png\",\"width\":32,\"height\":32,\"caption\":\"FAQ UOL Produtos Digitais\"},\"image\":{\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/person\/ca471cdebf5cc77ad5e5060a3aad80c8\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/97a1f074c859e56190cc8daf6e1d4a12?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/97a1f074c859e56190cc8daf6e1d4a12?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/faq.uol.com.br\"],\"url\":\"https:\/\/faq.uol.com.br\/uolpd\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vou perder acesso ao meu BOL Mail? - FAQ UOL Produtos Digitais","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/","og_locale":"pt_BR","og_type":"article","og_title":"Vou perder acesso ao meu BOL Mail? - FAQ UOL Produtos Digitais","og_description":"N&atilde;o.&nbsp;Voc&ecirc; continuar&aacute; com o acesso ao&nbsp;BOL Mail gratuito&nbsp;e poder&aacute; acess&aacute;-lo e utiliz&aacute;-lo&nbsp;somente pelo navegador&nbsp;de sua prefer&ecirc;ncia por meio do site do BOL ou diretamente acessando o&nbsp;Webmail BOL. Por&eacute;m, as contas BOL Mail gratuito sofrer&atilde;o as seguintes mudan&ccedil;as: N&atilde;o ser&atilde;o mais acessadas pelo aplicativo BOL Mail e gerenciadores de e-mail como Outlook, Thunderbird e etc.; O [&hellip;]","og_url":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/","og_site_name":"FAQ UOL Produtos Digitais","article_published_time":"2025-04-28T17:11:09+00:00","article_modified_time":"2025-04-28T17:11:10+00:00","og_image":[{"url":"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#article","isPartOf":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/"},"author":{"name":"admin","@id":"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/person\/ca471cdebf5cc77ad5e5060a3aad80c8"},"headline":"Vou perder acesso ao meu BOL Mail?","datePublished":"2025-04-28T17:11:09+00:00","dateModified":"2025-04-28T17:11:10+00:00","mainEntityOfPage":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/#organization"},"image":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#primaryimage"},"thumbnailUrl":"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png","articleSection":["Bol mail"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/","url":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/","name":"Vou perder acesso ao meu BOL Mail? - FAQ UOL Produtos Digitais","isPartOf":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/#website"},"primaryImageOfPage":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#primaryimage"},"image":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#primaryimage"},"thumbnailUrl":"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png","datePublished":"2025-04-28T17:11:09+00:00","dateModified":"2025-04-28T17:11:10+00:00","breadcrumb":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#primaryimage","url":"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png","contentUrl":"https:\/\/imguol.com.br\/p\/uolhost\/HOST\/p\/faq\/publicador\/69\/2022\/09\/14\/img-1---vou-perder-acesso-ao-meu-bol-mail-1663175277523_631x397.png"},{"@type":"BreadcrumbList","@id":"https:\/\/faq.uol.com.br\/uolpd\/vou-perder-acesso-ao-meu-bol-mail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/faq.uol.com.br\/uolpd\/"},{"@type":"ListItem","position":2,"name":"Vou perder acesso ao meu BOL Mail?"}]},{"@type":"WebSite","@id":"https:\/\/faq.uol.com.br\/uolpd\/#website","url":"https:\/\/faq.uol.com.br\/uolpd\/","name":"FAQ UOL Produtos Digitais","description":"","publisher":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/faq.uol.com.br\/uolpd\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/faq.uol.com.br\/uolpd\/#organization","name":"FAQ UOL Produtos Digitais","url":"https:\/\/faq.uol.com.br\/uolpd\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/logo\/image\/","url":"https:\/\/faq.uol.com.br\/uolpd\/wp-content\/uploads\/sites\/3\/2024\/05\/favicon.png","contentUrl":"https:\/\/faq.uol.com.br\/uolpd\/wp-content\/uploads\/sites\/3\/2024\/05\/favicon.png","width":32,"height":32,"caption":"FAQ UOL Produtos Digitais"},"image":{"@id":"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/person\/ca471cdebf5cc77ad5e5060a3aad80c8","name":"admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/faq.uol.com.br\/uolpd\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/97a1f074c859e56190cc8daf6e1d4a12?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97a1f074c859e56190cc8daf6e1d4a12?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/faq.uol.com.br"],"url":"https:\/\/faq.uol.com.br\/uolpd\/author\/admin\/"}]}},"category_names":["Bol mail"],"_links":{"self":[{"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/posts\/332"}],"collection":[{"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/comments?post=332"}],"version-history":[{"count":1,"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/posts\/332\/revisions"}],"predecessor-version":[{"id":1339,"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/posts\/332\/revisions\/1339"}],"wp:attachment":[{"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/media?parent=332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/categories?post=332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/faq.uol.com.br\/uolpd\/wp-json\/wp\/v2\/tags?post=332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}